{"id":3170,"date":"2021-04-29T01:58:24","date_gmt":"2021-04-29T01:58:24","guid":{"rendered":"https:\/\/fabriciob.ar\/web\/?p=3170"},"modified":"2021-04-29T01:58:24","modified_gmt":"2021-04-29T01:58:24","slug":"manual-del-conductor","status":"publish","type":"post","link":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/","title":{"rendered":"Manual del Conductor"},"content":{"rendered":"<p><a href=\"https:\/\/fabriciob.ar\/web\/wp-content\/uploads\/2021\/04\/Manual-del-Conductor-2020-Digital.pdf\">Manual-del-Conductor-2020-Digital<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manual-del-Conductor-2020-Digital<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-3170","post","type-post","status-publish","format-standard","hentry","category-info-util"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manual del Conductor - Fabricio Bolatti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manual del Conductor - Fabricio Bolatti\" \/>\n<meta property=\"og:description\" content=\"Manual-del-Conductor-2020-Digital\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/\" \/>\n<meta property=\"og:site_name\" content=\"Fabricio Bolatti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fabriciobolattiK\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T01:58:24+00:00\" \/>\n<meta name=\"author\" content=\"Equipo Fabricio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fabriciobolatti\" \/>\n<meta name=\"twitter:site\" content=\"@fabriciobolatti\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Fabricio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/\"},\"author\":{\"name\":\"Equipo Fabricio\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#\\\/schema\\\/person\\\/d56dbc2f2489983c5270184312aab61b\"},\"headline\":\"Manual del Conductor\",\"datePublished\":\"2021-04-29T01:58:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/\"},\"wordCount\":5,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#organization\"},\"articleSection\":[\"INFO \u00daTIL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/\",\"url\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/\",\"name\":\"Manual del Conductor - Fabricio Bolatti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#website\"},\"datePublished\":\"2021-04-29T01:58:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/manual-del-conductor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manual del Conductor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/\",\"name\":\"Fabricio Bolatti\",\"description\":\"Sitio Oficial-Comunicaci\u00f3n institucional de la gesti\u00f3n legislativa del concejal Fabricio Bolatti con los vecinos y vecinas de la ciudad de Resistencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#organization\",\"name\":\"Fabricio Bolatti-Sitio Oficial\",\"url\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cropped-fb-en-el-concejo-a-red-2-1.png\",\"contentUrl\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cropped-fb-en-el-concejo-a-red-2-1.png\",\"width\":512,\"height\":512,\"caption\":\"Fabricio Bolatti-Sitio Oficial\"},\"image\":{\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fabriciobolattiK\\\/\",\"https:\\\/\\\/x.com\\\/fabriciobolatti\",\"https:\\\/\\\/www.instagram.com\\\/fabriciobolatti\\\/?igshid=7ztsgzj0mwql\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWLMPKJZG1JgX9U29Pra3ng\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/#\\\/schema\\\/person\\\/d56dbc2f2489983c5270184312aab61b\",\"name\":\"Equipo Fabricio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d8e99352a71f2ac7e650885bc7721fe9d667070a36c2a5bb86aab909b8cf626?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d8e99352a71f2ac7e650885bc7721fe9d667070a36c2a5bb86aab909b8cf626?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d8e99352a71f2ac7e650885bc7721fe9d667070a36c2a5bb86aab909b8cf626?s=96&d=mm&r=g\",\"caption\":\"Equipo Fabricio\"},\"url\":\"https:\\\/\\\/fabriciob.ar\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manual del Conductor - Fabricio Bolatti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/","og_locale":"es_ES","og_type":"article","og_title":"Manual del Conductor - Fabricio Bolatti","og_description":"Manual-del-Conductor-2020-Digital","og_url":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/","og_site_name":"Fabricio Bolatti","article_publisher":"https:\/\/www.facebook.com\/fabriciobolattiK\/","article_published_time":"2021-04-29T01:58:24+00:00","author":"Equipo Fabricio","twitter_card":"summary_large_image","twitter_creator":"@fabriciobolatti","twitter_site":"@fabriciobolatti","twitter_misc":{"Escrito por":"Equipo Fabricio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/#article","isPartOf":{"@id":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/"},"author":{"name":"Equipo Fabricio","@id":"https:\/\/fabriciob.ar\/web\/#\/schema\/person\/d56dbc2f2489983c5270184312aab61b"},"headline":"Manual del Conductor","datePublished":"2021-04-29T01:58:24+00:00","mainEntityOfPage":{"@id":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/"},"wordCount":5,"commentCount":0,"publisher":{"@id":"https:\/\/fabriciob.ar\/web\/#organization"},"articleSection":["INFO \u00daTIL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fabriciob.ar\/web\/manual-del-conductor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/","url":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/","name":"Manual del Conductor - Fabricio Bolatti","isPartOf":{"@id":"https:\/\/fabriciob.ar\/web\/#website"},"datePublished":"2021-04-29T01:58:24+00:00","breadcrumb":{"@id":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fabriciob.ar\/web\/manual-del-conductor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fabriciob.ar\/web\/manual-del-conductor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fabriciob.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Manual del Conductor"}]},{"@type":"WebSite","@id":"https:\/\/fabriciob.ar\/web\/#website","url":"https:\/\/fabriciob.ar\/web\/","name":"Fabricio Bolatti","description":"Sitio Oficial-Comunicaci\u00f3n institucional de la gesti\u00f3n legislativa del concejal Fabricio Bolatti con los vecinos y vecinas de la ciudad de Resistencia","publisher":{"@id":"https:\/\/fabriciob.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fabriciob.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fabriciob.ar\/web\/#organization","name":"Fabricio Bolatti-Sitio Oficial","url":"https:\/\/fabriciob.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fabriciob.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fabriciob.ar\/web\/wp-content\/uploads\/2020\/12\/cropped-fb-en-el-concejo-a-red-2-1.png","contentUrl":"https:\/\/fabriciob.ar\/web\/wp-content\/uploads\/2020\/12\/cropped-fb-en-el-concejo-a-red-2-1.png","width":512,"height":512,"caption":"Fabricio Bolatti-Sitio Oficial"},"image":{"@id":"https:\/\/fabriciob.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fabriciobolattiK\/","https:\/\/x.com\/fabriciobolatti","https:\/\/www.instagram.com\/fabriciobolatti\/?igshid=7ztsgzj0mwql","https:\/\/www.youtube.com\/channel\/UCWLMPKJZG1JgX9U29Pra3ng"]},{"@type":"Person","@id":"https:\/\/fabriciob.ar\/web\/#\/schema\/person\/d56dbc2f2489983c5270184312aab61b","name":"Equipo Fabricio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9d8e99352a71f2ac7e650885bc7721fe9d667070a36c2a5bb86aab909b8cf626?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d8e99352a71f2ac7e650885bc7721fe9d667070a36c2a5bb86aab909b8cf626?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d8e99352a71f2ac7e650885bc7721fe9d667070a36c2a5bb86aab909b8cf626?s=96&d=mm&r=g","caption":"Equipo Fabricio"},"url":"https:\/\/fabriciob.ar\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/posts\/3170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/comments?post=3170"}],"version-history":[{"count":0,"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/posts\/3170\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/media?parent=3170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/categories?post=3170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fabriciob.ar\/web\/wp-json\/wp\/v2\/tags?post=3170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}